{"id":234,"count":1,"description":"","link":"https:\/\/teachchildrenmeditation.com\/es\/category\/harveyweinstein\/","name":"Harveyweinstein","slug":"harveyweinstein","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>harveyweinstein Archives - Teaching Children Meditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teachchildrenmeditation.com\/es\/category\/harveyweinstein\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"harveyweinstein Archives - Teaching Children Meditation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teachchildrenmeditation.com\/es\/category\/harveyweinstein\/\" \/>\n<meta property=\"og:site_name\" content=\"Teaching Children Meditation\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/category\\\/harveyweinstein\\\/\",\"url\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/category\\\/harveyweinstein\\\/\",\"name\":\"harveyweinstein Archives - Teaching Children Meditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/category\\\/harveyweinstein\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/category\\\/harveyweinstein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"harveyweinstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/#website\",\"url\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/\",\"name\":\"Teaching Children Meditation\",\"description\":\"accredited and award-winning\",\"publisher\":{\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/#organization\",\"name\":\"Connected Kids Ltd\",\"url\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/files\\\/2021\\\/04\\\/logo2CK-3.png\",\"contentUrl\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/files\\\/2021\\\/04\\\/logo2CK-3.png\",\"width\":472,\"height\":470,\"caption\":\"Connected Kids Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/teachchildrenmeditation.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/connectedkids\",\"https:\\\/\\\/www.instagram.com\\\/connectedkids\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"harveyweinstein Archives - Teaching Children Meditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teachchildrenmeditation.com\/es\/category\/harveyweinstein\/","og_locale":"es_ES","og_type":"article","og_title":"harveyweinstein Archives - Teaching Children Meditation","og_url":"https:\/\/teachchildrenmeditation.com\/es\/category\/harveyweinstein\/","og_site_name":"Teaching Children Meditation","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/teachchildrenmeditation.com\/category\/harveyweinstein\/","url":"https:\/\/teachchildrenmeditation.com\/category\/harveyweinstein\/","name":"harveyweinstein Archives - Teaching Children Meditation","isPartOf":{"@id":"https:\/\/teachchildrenmeditation.com\/#website"},"breadcrumb":{"@id":"https:\/\/teachchildrenmeditation.com\/category\/harveyweinstein\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/teachchildrenmeditation.com\/category\/harveyweinstein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teachchildrenmeditation.com\/"},{"@type":"ListItem","position":2,"name":"harveyweinstein"}]},{"@type":"WebSite","@id":"https:\/\/teachchildrenmeditation.com\/#website","url":"https:\/\/teachchildrenmeditation.com\/","name":"Ense\u00f1ar a los ni\u00f1os a meditar","description":"acreditado y premiado","publisher":{"@id":"https:\/\/teachchildrenmeditation.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teachchildrenmeditation.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/teachchildrenmeditation.com\/#organization","name":"Connected Kids Ltd","url":"https:\/\/teachchildrenmeditation.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/teachchildrenmeditation.com\/#\/schema\/logo\/image\/","url":"https:\/\/teachchildrenmeditation.com\/files\/2021\/04\/logo2CK-3.png","contentUrl":"https:\/\/teachchildrenmeditation.com\/files\/2021\/04\/logo2CK-3.png","width":472,"height":470,"caption":"Connected Kids Ltd"},"image":{"@id":"https:\/\/teachchildrenmeditation.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/connectedkids","https:\/\/www.instagram.com\/connectedkids\/"]}]}},"_links":{"self":[{"href":"https:\/\/teachchildrenmeditation.com\/es\/wp-json\/wp\/v2\/categories\/234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teachchildrenmeditation.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/teachchildrenmeditation.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/teachchildrenmeditation.com\/es\/wp-json\/wp\/v2\/posts?categories=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}